{"id":1251,"count":5,"description":"","link":"https:\/\/cnspeedone.com\/it\/tag\/countertop-seam-setter\/","name":"countertop seam setter","slug":"countertop-seam-setter","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/cnspeedone.com\/it\/wp-json\/wp\/v2\/tags\/1251"}],"collection":[{"href":"https:\/\/cnspeedone.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/cnspeedone.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/cnspeedone.com\/it\/wp-json\/wp\/v2\/posts?tags=1251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}